{"id":31,"date":"2025-01-06T04:46:25","date_gmt":"2025-01-06T04:46:25","guid":{"rendered":"https:\/\/modave.presslayouts.com\/dummy\/?page_id=31"},"modified":"2025-06-09T06:33:47","modified_gmt":"2025-06-09T06:33:47","slug":"home-fashion-luxeliving","status":"publish","type":"page","link":"https:\/\/modave.presslayouts.com\/dummy\/home-fashion-luxeliving\/","title":{"rendered":"Home Fashion LuxeLiving"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"31\" class=\"elementor elementor-31\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a9ea724 e-con-full e-flex e-con e-parent\" data-id=\"a9ea724\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=SjJhuZQlkbA&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-video-embed\" role=\"presentation\"><\/div>\n\t\t\t\t\t\t<\/div>\t\t<div class=\"elementor-element elementor-element-0ff8cec elementor-widget elementor-widget-pls-heading\" data-id=\"0ff8cec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-header-73952\" class=\"pls-element pls-heading pls-text-left\">\t\n\t\t\t\n\t\t\t<div class=\"heading-wrap\">\n\t\t\t<h2 class=\"heading-title\">Winter Warmth<\/h2>\t\t<\/div>\n\t\t\n    \t\t<div class=\"heading-tagline\"> Stay cozy and fashionable with our winter collection. <\/div>\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22f7db6 elementor-widget elementor-widget-pls-button\" data-id=\"22f7db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-button-17929\" class=\"pls-element pls-button\">\n\t<a class=\"button btn-style-flat\" href=\"#\" >\n\t\tExplore Collection\t<\/a>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3e99f99 e-flex e-con-boxed e-con e-parent\" data-id=\"3e99f99\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-96d168f elementor-widget elementor-widget-pls-heading\" data-id=\"96d168f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-header-84965\" class=\"pls-element pls-heading pls-text-center\">\t\n\t\t\t\n\t\t\t<div class=\"heading-wrap\">\n\t\t\t<h2 class=\"heading-title\">Today's Top Picks<\/h2>\t\t<\/div>\n\t\t\n    \t\t<div class=\"heading-tagline\"> Fresh styles just in! Elevate your look. <\/div>\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c4d4da elementor-widget elementor-widget-pls-products-grid-slider\" data-id=\"7c4d4da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-products-grid-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-products-grid-slider-64904\" class=\"pls-element pls-products-grid-slider woocommerce products-slider\">\n\t\t\n\t<div class=\"woocommerce columns-4 \">\t<div id=\"section-80962\" class=\"pls-slider swiper row\">\n\t\t<div class=\"products products-wrap product-style-1 grid-view swiper-wrapper slider-col-xl-4 slider-col-lg- slider-col-md-3 slider-col-2\" data-slider_options=\"{&quot;slider_loop&quot;:false,&quot;slider_autoplay&quot;:false,&quot;slider_autoplay_delay&quot;:&quot;1500&quot;,&quot;slider_autoplay_speed&quot;:&quot;1500&quot;,&quot;slider_pause_on_hover&quot;:false,&quot;slider_rewind&quot;:false,&quot;slider_autoHeigh&quot;:false,&quot;slider_touchDrag&quot;:true,&quot;slider_touchDrag_mobile&quot;:true,&quot;slider_navigation&quot;:true,&quot;slider_pagination&quot;:false,&quot;slider_scrollbar&quot;:false,&quot;slider_centered&quot;:false,&quot;slider_effect&quot;:&quot;slide&quot;,&quot;slider_spaceBetween&quot;:0,&quot;slides_to_show&quot;:&quot;4&quot;,&quot;slides_to_show_tablet&quot;:3,&quot;slides_to_show_mobile&quot;:2,&quot;slides_to_scroll&quot;:1}\" >\n\n\n<div class=\"swiper-slide product type-product post-1172 status-publish first instock product_cat-clothing product_cat-women has-post-thumbnail featured shipping-taxable purchasable product-type-simple\">\t \n\t\n<div class=\"pls-product-inner\">\n\t\t\n\t<div class=\"pls-product-image\">\n\t\t<div class=\"pls-product-labels\"><span class=\"featured\">Hot<\/span><\/div><a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/v-neck-pure-cotton-t-shirt\/\" class=\"woocommerce-LoopProduct-link\" target=\"_self\" aria-label=\"V-Neck Pure Cotton T-shirt\"><img fetchpriority=\"high\" decoding=\"async\" width=\"420\" height=\"560\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail front-image\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg 720w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1-90x120.jpg 90w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/><img decoding=\"async\" width=\"420\" height=\"560\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-420x560.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail hover-image\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-420x560.jpg 420w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-240x320.jpg 240w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-435x580.jpg 435w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-90x120.jpg 90w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2.jpg 720w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/><\/a>\t\t<div class=\"pls-product-icons\">\n\t\t\t\t\t\r\n\t\t<div class=\"pls-whishlist-btn\">\r\n\t\t\t<a href=\"?add-to-wishlist=1172\" class=\"woosw-btn woosw-btn-1172\" data-id=\"1172\" data-product_name=\"V-Neck Pure Cotton T-shirt\" data-product_image=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" rel=\"nofollow\" aria-label=\"Add to wishlist\">Add to wishlist<\/a>\t\t<\/div>\t\t\r\n\t\t\t\r\n\t\t<div class=\"pls-compare-btn\">\r\n\t\t\t<a href=\"?add-to-compare=1172\" class=\"woosc-btn woosc-btn-1172 \" rel=\"nofollow\" data-text=\"Compare\" data-text_added=\"Compare\" data-id=\"1172\" data-product_id=\"1172\" data-product_name=\"V-Neck Pure Cotton T-shirt\" data-product_image=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\">Compare<\/a>\t\t<\/div>\r\n\t\t\t\t\r\n\t\t<div class=\"pls-quickview-button\">\r\n\t\t\t<a class=\"pls-quickview-btn \" href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/v-neck-pure-cotton-t-shirt\/\" data-id=\"1172\">Quick View<\/a>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"pls-product-actions\">\n\t\t\t\t\t\r\n\t\t<div class=\"pls-cart-button\">\r\n\t\t\t<a href=\"\/dummy\/wp-json\/wp\/v2\/pages\/31?add-to-cart=1172\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1172\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"1172\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;V-Neck Pure Cotton T-shirt&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;V-Neck Pure Cotton T-shirt&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t\t <\/div>\r\n\t\t\t\t<\/div>\n\t<\/div>\n\t<div class=\"pls-product-info\">\n\t\t<h3 class=\"product-title\"><a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/v-neck-pure-cotton-t-shirt\/\" target=\"_self\">V-Neck Pure Cotton T-shirt<\/a><\/h3>\n<div class=\"pls-star-rating\">\n\t<div class=\"star-rating\" role=\"img\" aria-label=\"Rated 0 out of 5\"><span style=\"width:0%\">Rated <strong class=\"rating\">0<\/strong> out of 5<\/span><\/div>\t\t<span class=\"rating-counts\">\n\t\t\t(0)\t\t<\/span>\n\t<\/div>\n\t<div class=\"pls-product-price\">\n\t\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>59.99<\/span><\/span>\n\t<\/div>\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\t \n<\/div>\n\n<div class=\"swiper-slide product type-product post-1170 status-publish instock product_cat-accessories product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-simple\">\t \n\t\n<div class=\"pls-product-inner\">\n\t\t\n\t<div class=\"pls-product-image\">\n\t\t<div class=\"pls-product-labels\"><span class=\"on-sale\">-20% <\/span><\/div><a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/polarized-sunglasses\/\" class=\"woocommerce-LoopProduct-link\" target=\"_self\" aria-label=\"Polarized Sunglasses\"><img fetchpriority=\"high\" decoding=\"async\" width=\"420\" height=\"560\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail front-image\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg 720w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1-90x120.jpg 90w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/><img decoding=\"async\" width=\"420\" height=\"560\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-420x560.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail hover-image\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-420x560.jpg 420w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-240x320.jpg 240w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-435x580.jpg 435w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-90x120.jpg 90w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2.jpg 720w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/><\/a>\t\t<div class=\"pls-product-icons\">\n\t\t\t\t\t\r\n\t\t<div class=\"pls-whishlist-btn\">\r\n\t\t\t<a href=\"?add-to-wishlist=1170\" class=\"woosw-btn woosw-btn-1170\" data-id=\"1170\" data-product_name=\"Polarized Sunglasses\" data-product_image=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" rel=\"nofollow\" aria-label=\"Add to wishlist\">Add to wishlist<\/a>\t\t<\/div>\t\t\r\n\t\t\t\r\n\t\t<div class=\"pls-compare-btn\">\r\n\t\t\t<a href=\"?add-to-compare=1170\" class=\"woosc-btn woosc-btn-1170 \" rel=\"nofollow\" data-text=\"Compare\" data-text_added=\"Compare\" data-id=\"1170\" data-product_id=\"1170\" data-product_name=\"Polarized Sunglasses\" data-product_image=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\">Compare<\/a>\t\t<\/div>\r\n\t\t\t\t\r\n\t\t<div class=\"pls-quickview-button\">\r\n\t\t\t<a class=\"pls-quickview-btn \" href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/polarized-sunglasses\/\" data-id=\"1170\">Quick View<\/a>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t\r\n\t\t<div class=\"pls-product-sale-marquee\">\r\n\t\t\t<div class=\"pls-marquee\">\r\n\t\t\t\t<div class=\"pls-marquee-items\">\r\n\t\t\t\t\t<div class=\"pls-marquee-item\">Hot Sale <span class=\"on-sale\">20% <\/span> off.<\/div><div class=\"pls-marquee-separator\"><\/div><div class=\"pls-marquee-item\">Hot Sale <span class=\"on-sale\">20% <\/span> off.<\/div><div class=\"pls-marquee-separator\"><\/div><div class=\"pls-marquee-item\">Hot Sale <span class=\"on-sale\">20% <\/span> off.<\/div><div class=\"pls-marquee-separator\"><\/div><div class=\"pls-marquee-item\">Hot Sale <span class=\"on-sale\">20% <\/span> off.<\/div><div class=\"pls-marquee-separator\"><\/div><div class=\"pls-marquee-item\">Hot Sale <span class=\"on-sale\">20% <\/span> off.<\/div><div class=\"pls-marquee-separator\"><\/div>\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"pls-marquee\">\r\n\t\t\t\t<div class=\"pls-marquee-items\">\r\n\t\t\t\t\t<div class=\"pls-marquee-item\">Hot Sale <span class=\"on-sale\">20% <\/span> off.<\/div><div class=\"pls-marquee-separator\"><\/div><div class=\"pls-marquee-item\">Hot Sale <span class=\"on-sale\">20% <\/span> off.<\/div><div class=\"pls-marquee-separator\"><\/div><div class=\"pls-marquee-item\">Hot Sale <span class=\"on-sale\">20% <\/span> off.<\/div><div class=\"pls-marquee-separator\"><\/div><div class=\"pls-marquee-item\">Hot Sale <span class=\"on-sale\">20% <\/span> off.<\/div><div class=\"pls-marquee-separator\"><\/div><div class=\"pls-marquee-item\">Hot Sale <span class=\"on-sale\">20% <\/span> off.<\/div><div class=\"pls-marquee-separator\"><\/div>\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div> \r\n\t\t\t\t\t\t<div class=\"pls-product-actions\">\n\t\t\t\t\t\r\n\t\t<div class=\"pls-cart-button\">\r\n\t\t\t<a href=\"\/dummy\/wp-json\/wp\/v2\/pages\/31?add-to-cart=1170\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1170\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"1170\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Polarized Sunglasses&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Polarized Sunglasses&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t\t <\/div>\r\n\t\t\t\t<\/div>\n\t<\/div>\n\t<div class=\"pls-product-info\">\n\t\t<h3 class=\"product-title\"><a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/polarized-sunglasses\/\" target=\"_self\">Polarized Sunglasses<\/a><\/h3>\n<div class=\"pls-star-rating\">\n\t<div class=\"star-rating\" role=\"img\" aria-label=\"Rated 0 out of 5\"><span style=\"width:0%\">Rated <strong class=\"rating\">0<\/strong> out of 5<\/span><\/div>\t\t<span class=\"rating-counts\">\n\t\t\t(0)\t\t<\/span>\n\t<\/div>\n\t<div class=\"pls-product-price\">\n\t\t<span class=\"price\"><ins><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>79.99<\/span><\/ins> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>99.99<\/span><\/del><\/span>\n\t<\/div>\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\t \n<\/div>\n\n<div class=\"swiper-slide product type-product post-1169 status-publish instock product_cat-clothing product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable has-default-attributes\">\t \n\t\n<div class=\"pls-product-inner\">\n\t\t\n\t<div class=\"pls-product-image\">\n\t\t<div class=\"pls-product-labels\"><span class=\"on-sale\">-44% <\/span><\/div><a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/ramie-shirt-with-pockets\/\" class=\"woocommerce-LoopProduct-link\" target=\"_self\" aria-label=\"Ramie Shirt with Pockets\"><img fetchpriority=\"high\" decoding=\"async\" width=\"420\" height=\"560\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail front-image\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg 720w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1-90x120.jpg 90w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/><img decoding=\"async\" width=\"420\" height=\"560\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-420x560.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail hover-image\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-420x560.jpg 420w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-240x320.jpg 240w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-435x580.jpg 435w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-90x120.jpg 90w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2.jpg 720w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/><\/a>\t\t\t\t<div class=\"pls-product-countdown-timer\">\r\n\t\t\t\t\t<div class=\"pls-product-countdown\" data-end-date=\"2027-12-31 23:59:59\" data-timezone=\"+00:00\" data-countdown-style=\"countdown-text\"><\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"pls-product-icons\">\n\t\t\t\t\t\r\n\t\t<div class=\"pls-whishlist-btn\">\r\n\t\t\t<a href=\"?add-to-wishlist=1169\" class=\"woosw-btn woosw-btn-1169\" data-id=\"1169\" data-product_name=\"Ramie Shirt with Pockets\" data-product_image=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" rel=\"nofollow\" aria-label=\"Add to wishlist\">Add to wishlist<\/a>\t\t<\/div>\t\t\r\n\t\t\t\r\n\t\t<div class=\"pls-compare-btn\">\r\n\t\t\t<a href=\"?add-to-compare=1169\" class=\"woosc-btn woosc-btn-1169 \" rel=\"nofollow\" data-text=\"Compare\" data-text_added=\"Compare\" data-id=\"1169\" data-product_id=\"1169\" data-product_name=\"Ramie Shirt with Pockets\" data-product_image=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\">Compare<\/a>\t\t<\/div>\r\n\t\t\t\t\r\n\t\t<div class=\"pls-quickview-button\">\r\n\t\t\t<a class=\"pls-quickview-btn \" href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/ramie-shirt-with-pockets\/\" data-id=\"1169\">Quick View<\/a>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"pls-product-actions\">\n\t\t\t\t\t\r\n\t\t<div class=\"pls-cart-button\">\r\n\t\t\t<a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/ramie-shirt-with-pockets\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1169\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"1169\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Ramie Shirt with Pockets&rdquo;\" rel=\"nofollow\">Select options<\/a>\t\t <\/div>\r\n\t\t\t\t<\/div>\n\t<\/div>\n\t<div class=\"pls-product-info\">\n\t\t<h3 class=\"product-title\"><a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/ramie-shirt-with-pockets\/\" target=\"_self\">Ramie Shirt with Pockets<\/a><\/h3>\n<div class=\"pls-star-rating\">\n\t<div class=\"star-rating\" role=\"img\" aria-label=\"Rated 0 out of 5\"><span style=\"width:0%\">Rated <strong class=\"rating\">0<\/strong> out of 5<\/span><\/div>\t\t<span class=\"rating-counts\">\n\t\t\t(0)\t\t<\/span>\n\t<\/div>\n\t<div class=\"pls-product-price\">\n\t\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>49.99<\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>89.99<\/span><span class=\"screen-reader-text\">Price range: &#036;49.99 through &#036;89.99<\/span><\/span>\n\t<\/div>\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\t \n<\/div>\n\n<div class=\"swiper-slide product type-product post-1168 status-publish last instock product_cat-women has-post-thumbnail shipping-taxable purchasable product-type-variable has-default-attributes\">\t \n\t\n<div class=\"pls-product-inner\">\n\t\t\n\t<div class=\"pls-product-image\">\n\t\t<a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/shoulder-straps-fitted-top\/\" class=\"woocommerce-LoopProduct-link\" target=\"_self\" aria-label=\"Shoulder Straps Fitted Top\"><img fetchpriority=\"high\" decoding=\"async\" width=\"420\" height=\"560\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail front-image\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg 720w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1-90x120.jpg 90w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/><img decoding=\"async\" width=\"420\" height=\"560\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail hover-image\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg 720w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1-90x120.jpg 90w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/><\/a>\t\t<div class=\"pls-product-icons\">\n\t\t\t\t\t\r\n\t\t<div class=\"pls-whishlist-btn\">\r\n\t\t\t<a href=\"?add-to-wishlist=1168\" class=\"woosw-btn woosw-btn-1168\" data-id=\"1168\" data-product_name=\"Shoulder Straps Fitted Top\" data-product_image=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" rel=\"nofollow\" aria-label=\"Add to wishlist\">Add to wishlist<\/a>\t\t<\/div>\t\t\r\n\t\t\t\r\n\t\t<div class=\"pls-compare-btn\">\r\n\t\t\t<a href=\"?add-to-compare=1168\" class=\"woosc-btn woosc-btn-1168 \" rel=\"nofollow\" data-text=\"Compare\" data-text_added=\"Compare\" data-id=\"1168\" data-product_id=\"1168\" data-product_name=\"Shoulder Straps Fitted Top\" data-product_image=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\">Compare<\/a>\t\t<\/div>\r\n\t\t\t\t\r\n\t\t<div class=\"pls-quickview-button\">\r\n\t\t\t<a class=\"pls-quickview-btn \" href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/shoulder-straps-fitted-top\/\" data-id=\"1168\">Quick View<\/a>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"pls-product-actions\">\n\t\t\t\t\t\r\n\t\t<div class=\"pls-cart-button\">\r\n\t\t\t<a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/shoulder-straps-fitted-top\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1168\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"1168\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Shoulder Straps Fitted Top&rdquo;\" rel=\"nofollow\">Select options<\/a>\t\t <\/div>\r\n\t\t\t\t<\/div>\n\t<\/div>\n\t<div class=\"pls-product-info\">\n\t\t<h3 class=\"product-title\"><a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/shoulder-straps-fitted-top\/\" target=\"_self\">Shoulder Straps Fitted Top<\/a><\/h3>\n<div class=\"pls-star-rating\">\n\t<div class=\"star-rating\" role=\"img\" aria-label=\"Rated 0 out of 5\"><span style=\"width:0%\">Rated <strong class=\"rating\">0<\/strong> out of 5<\/span><\/div>\t\t<span class=\"rating-counts\">\n\t\t\t(0)\t\t<\/span>\n\t<\/div>\n\t<div class=\"pls-product-price\">\n\t\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>69.99<\/span><\/span>\n\t<\/div>\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\t \n<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f871d63 e-con-full e-flex e-con e-parent\" data-id=\"f871d63\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f8ecbf elementor-widget elementor-widget-pls-marquee\" data-id=\"9f8ecbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-marquee.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-marquee-74571\" class=\"pls-element pls-marquee pls-marquee-hover-paused\">\n\t<div class=\"pls-marquee-items\">\n\t\t\t\t\t<div class=\"pls-marquee-item\">\n\t\t\t\t\t\t\t\t<span class=\"pls-marquee-item-text\">Free shipping on all orders over $20.00<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"pls-marquee-item-icon\"><i aria-hidden=\"true\" class=\"picon-energy\"><\/i><\/div>\t\t\t\t\t<div class=\"pls-marquee-item\">\n\t\t\t\t\t\t\t\t<span class=\"pls-marquee-item-text\">Returns are free within 14 days<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"pls-marquee-item-icon\"><i aria-hidden=\"true\" class=\"picon-energy\"><\/i><\/div>\t\t\t\t\t<div class=\"pls-marquee-item\">\n\t\t\t\t\t\t\t\t<span class=\"pls-marquee-item-text\">Free shipping on all orders over $20.00<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"pls-marquee-item-icon\"><i aria-hidden=\"true\" class=\"picon-energy\"><\/i><\/div>\t\t\t\t\t<div class=\"pls-marquee-item\">\n\t\t\t\t\t\t\t\t<span class=\"pls-marquee-item-text\">Returns are free within 14 days<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"pls-marquee-item-icon\"><i aria-hidden=\"true\" class=\"picon-energy\"><\/i><\/div>\t\t\t\t\t<div class=\"pls-marquee-item\">\n\t\t\t\t\t\t\t\t<span class=\"pls-marquee-item-text\">Free shipping on all orders over $20.00<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"pls-marquee-item-icon\"><i aria-hidden=\"true\" class=\"picon-energy\"><\/i><\/div>\t\t\t<\/div>\n\t\n\t<!-- Duplicate for Repeater -->\n\t<div class=\"pls-marquee-items\" aria-hidden=\"true\">\n\t\t\t\t\t<div class=\"pls-marquee-item\">\n\t\t\t\t\t\t\t\t<span class=\"pls-marquee-item-text\">Free shipping on all orders over $20.00<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"pls-marquee-item-icon\"><i aria-hidden=\"true\" class=\"picon-energy\"><\/i><\/div>\t\t\t\t\t<div class=\"pls-marquee-item\">\n\t\t\t\t\t\t\t\t<span class=\"pls-marquee-item-text\">Returns are free within 14 days<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"pls-marquee-item-icon\"><i aria-hidden=\"true\" class=\"picon-energy\"><\/i><\/div>\t\t\t\t\t<div class=\"pls-marquee-item\">\n\t\t\t\t\t\t\t\t<span class=\"pls-marquee-item-text\">Free shipping on all orders over $20.00<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"pls-marquee-item-icon\"><i aria-hidden=\"true\" class=\"picon-energy\"><\/i><\/div>\t\t\t\t\t<div class=\"pls-marquee-item\">\n\t\t\t\t\t\t\t\t<span class=\"pls-marquee-item-text\">Returns are free within 14 days<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"pls-marquee-item-icon\"><i aria-hidden=\"true\" class=\"picon-energy\"><\/i><\/div>\t\t\t\t\t<div class=\"pls-marquee-item\">\n\t\t\t\t\t\t\t\t<span class=\"pls-marquee-item-text\">Free shipping on all orders over $20.00<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"pls-marquee-item-icon\"><i aria-hidden=\"true\" class=\"picon-energy\"><\/i><\/div>\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a43754 e-flex e-con-boxed e-con e-parent\" data-id=\"7a43754\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-87b0099 elementor-widget elementor-widget-pls-heading\" data-id=\"87b0099\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-header-35008\" class=\"pls-element pls-heading pls-text-center\">\t\n\t\t\t\n\t\t\t<div class=\"heading-wrap\">\n\t\t\t<h2 class=\"heading-title\">Shop by categories<\/h2>\t\t<\/div>\n\t\t\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cebe286 e-con-full e-flex e-con e-child\" data-id=\"cebe286\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-85ba3f9 e-con-full e-flex e-con e-child\" data-id=\"85ba3f9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53e5723 elementor-widget elementor-widget-pls-banner\" data-id=\"53e5723\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-banner-31188\" class=\"pls-element pls-banner banner-zoom-out\">\n\t<div class=\"banner-wrapper\" >\n\t\t\t\t\t<div class=\"banner-image-wrap\">\t\t\t\n\t\t\t\t<div class=\"banner-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"410\" height=\"547\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-12-cat-1.jpg\" class=\"attachment-full size-full \" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-12-cat-1.jpg 410w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-12-cat-1-240x320.jpg 240w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-12-cat-1-90x120.jpg 90w\" sizes=\"(max-width: 410px) 100vw, 410px\" \/>\t\t\t\t<\/div>\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"banner-content-wrap\">\n\t\t\t\t<div class=\"banner-content\">\n\t\t\t\t\t<div class=\"banner-content-top\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"banner-content-bottom\">\n\t\t\t\t\t\t\t<div class=\"banner-button pls-button\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_self\" class=\"button btn-style-flat\">Women<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9dc7169 e-con-full e-flex e-con e-child\" data-id=\"9dc7169\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b96350 elementor-widget elementor-widget-pls-banner\" data-id=\"4b96350\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-banner-10260\" class=\"pls-element pls-banner banner-zoom-out\">\n\t<div class=\"banner-wrapper\" >\n\t\t\t\t\t<div class=\"banner-image-wrap\">\t\t\t\n\t\t\t\t<div class=\"banner-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"410\" height=\"259\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-12-cat-2.jpg\" class=\"attachment-full size-full \" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-12-cat-2.jpg 410w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-12-cat-2-90x57.jpg 90w\" sizes=\"(max-width: 410px) 100vw, 410px\" \/>\t\t\t\t<\/div>\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"banner-content-wrap\">\n\t\t\t\t<div class=\"banner-content\">\n\t\t\t\t\t<div class=\"banner-content-top\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"banner-content-bottom\">\n\t\t\t\t\t\t\t<div class=\"banner-button pls-button\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_self\" class=\"button btn-style-flat\">Promotion<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-595c611 elementor-widget elementor-widget-pls-banner\" data-id=\"595c611\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-banner-56675\" class=\"pls-element pls-banner banner-zoom-out\">\n\t<div class=\"banner-wrapper\" >\n\t\t\t\t\t<div class=\"banner-image-wrap\">\t\t\t\n\t\t\t\t<div class=\"banner-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"410\" height=\"259\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-12-cat-2.jpg\" class=\"attachment-full size-full \" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-12-cat-2.jpg 410w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-12-cat-2-90x57.jpg 90w\" sizes=\"(max-width: 410px) 100vw, 410px\" \/>\t\t\t\t<\/div>\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"banner-content-wrap\">\n\t\t\t\t<div class=\"banner-content\">\n\t\t\t\t\t<div class=\"banner-content-top\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"banner-content-bottom\">\n\t\t\t\t\t\t\t<div class=\"banner-button pls-button\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_self\" class=\"button btn-style-flat\">Accessories<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e0a817e e-con-full e-flex e-con e-child\" data-id=\"e0a817e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c0c873f elementor-widget elementor-widget-pls-banner\" data-id=\"c0c873f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-banner-47648\" class=\"pls-element pls-banner banner-zoom-out\">\n\t<div class=\"banner-wrapper\" >\n\t\t\t\t\t<div class=\"banner-image-wrap\">\t\t\t\n\t\t\t\t<div class=\"banner-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"410\" height=\"547\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-12-cat-1.jpg\" class=\"attachment-full size-full \" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-12-cat-1.jpg 410w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-12-cat-1-240x320.jpg 240w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-12-cat-1-90x120.jpg 90w\" sizes=\"(max-width: 410px) 100vw, 410px\" \/>\t\t\t\t<\/div>\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"banner-content-wrap\">\n\t\t\t\t<div class=\"banner-content\">\n\t\t\t\t\t<div class=\"banner-content-top\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"banner-content-bottom\">\n\t\t\t\t\t\t\t<div class=\"banner-button pls-button\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_self\" class=\"button btn-style-flat\">Men<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5fc9e15 e-con-full e-flex e-con e-parent\" data-id=\"5fc9e15\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-fdfd5ce e-con-full e-flex e-con e-child\" data-id=\"fdfd5ce\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-084f914 elementor-widget elementor-widget-pls-hotspot\" data-id=\"084f914\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-hotspot.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-hotspot-58650\" class=\"pls-element pls-hotspot\">\n\t<div class=\"pls-hotspot-wrapper\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-12-lookbook-1.jpg\" alt=\"Hotspot\">\n\t\t\t\t<div class=\"pls-hotspot-items\">\n\t\t\t\t\t\t\t<div class=\"pls-hotspot-item elementor-repeater-item-2e140e0\">\n\t\t\t\t\t<span class=\"pls-hotspot-item-point\"><\/span>\n\t\t\t\t\t<div class=\"pls-hotspot-content pls-hotspot-content-product pls-hotspot-content-top\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pls-hotspot-product\">\n\t\t\t\t\t\t\t\t<div class=\"pls-product-image\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/natural-fiber-shopper-bag\/\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" class=\"attachment- size-\" alt=\"Natural Fiber Shopper Bag\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg 720w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1-90x120.jpg 90w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pls-product-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"product-title\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/natural-fiber-shopper-bag\/\">\n\t\t\t\t\t\t\t\t\t\t\tNatural Fiber Shopper Bag\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"product-price\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span>79.99<\/bdi><\/span>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"product-quickview\">\n\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t<div class=\"pls-quickview-button\">\r\n\t\t\t<a class=\"pls-quickview-btn pls-hotspot-quickview\" href=\"https:\/\/modave.presslayouts.com\/dummy\/home-fashion-luxeliving\/\" data-id=\"1082\">Quick View<\/a>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-be67163 e-con-full e-flex e-con e-child\" data-id=\"be67163\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d7cea02 elementor-widget elementor-widget-pls-hotspot\" data-id=\"d7cea02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-hotspot.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-hotspot-88475\" class=\"pls-element pls-hotspot\">\n\t<div class=\"pls-hotspot-wrapper\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-12-lookbook-1.jpg\" alt=\"Hotspot\">\n\t\t\t\t<div class=\"pls-hotspot-items\">\n\t\t\t\t\t\t\t<div class=\"pls-hotspot-item elementor-repeater-item-2e140e0\">\n\t\t\t\t\t<span class=\"pls-hotspot-item-point\"><\/span>\n\t\t\t\t\t<div class=\"pls-hotspot-content pls-hotspot-content-product pls-hotspot-content-top\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pls-hotspot-product\">\n\t\t\t\t\t\t\t\t<div class=\"pls-product-image\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/stretch-strap-top\/\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" class=\"attachment- size-\" alt=\"Stretch strap top\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg 720w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1-90x120.jpg 90w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pls-product-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"product-title\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/stretch-strap-top\/\">\n\t\t\t\t\t\t\t\t\t\t\tStretch strap top\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"product-price\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span>109.99<\/bdi><\/span>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"product-quickview\">\n\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t<div class=\"pls-quickview-button\">\r\n\t\t\t<a class=\"pls-quickview-btn pls-hotspot-quickview\" href=\"https:\/\/modave.presslayouts.com\/dummy\/home-fashion-luxeliving\/\" data-id=\"1086\">Quick View<\/a>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9e11b48 e-flex e-con-boxed e-con e-parent\" data-id=\"9e11b48\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f94439c elementor-widget elementor-widget-pls-heading\" data-id=\"f94439c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-header-55811\" class=\"pls-element pls-heading pls-text-center\">\t\n\t\t\t\n\t\t\t<div class=\"heading-wrap\">\n\t\t\t<h2 class=\"heading-title\">Top Trending<\/h2>\t\t<\/div>\n\t\t\n    \t\t<div class=\"heading-tagline\"> Browse our Top Trending: the hottest picks loved by all.  <\/div>\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e1199d elementor-widget elementor-widget-pls-products-grid-slider\" data-id=\"8e1199d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-products-grid-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-products-grid-slider-97346\" class=\"pls-element pls-products-grid-slider woocommerce products-slider\">\n\t\t\n\t<div class=\"woocommerce columns-4 \">\t<div id=\"section-83632\" class=\"pls-slider swiper row\">\n\t\t<div class=\"products products-wrap product-style-1 grid-view swiper-wrapper slider-col-xl-4 slider-col-lg- slider-col-md-3 slider-col-2\" data-slider_options=\"{&quot;slider_loop&quot;:false,&quot;slider_autoplay&quot;:false,&quot;slider_autoplay_delay&quot;:&quot;1500&quot;,&quot;slider_autoplay_speed&quot;:&quot;1500&quot;,&quot;slider_pause_on_hover&quot;:false,&quot;slider_rewind&quot;:false,&quot;slider_autoHeigh&quot;:false,&quot;slider_touchDrag&quot;:true,&quot;slider_touchDrag_mobile&quot;:true,&quot;slider_navigation&quot;:true,&quot;slider_pagination&quot;:false,&quot;slider_scrollbar&quot;:false,&quot;slider_centered&quot;:false,&quot;slider_effect&quot;:&quot;slide&quot;,&quot;slider_spaceBetween&quot;:0,&quot;slides_to_show&quot;:&quot;4&quot;,&quot;slides_to_show_tablet&quot;:3,&quot;slides_to_show_mobile&quot;:2,&quot;slides_to_scroll&quot;:1}\" >\n\n\n<div class=\"swiper-slide product type-product post-1172 status-publish first instock product_cat-clothing product_cat-women has-post-thumbnail featured shipping-taxable purchasable product-type-simple\">\t \n\t\n<div class=\"pls-product-inner\">\n\t\t\n\t<div class=\"pls-product-image\">\n\t\t<div class=\"pls-product-labels\"><span class=\"featured\">Hot<\/span><\/div><a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/v-neck-pure-cotton-t-shirt\/\" class=\"woocommerce-LoopProduct-link\" target=\"_self\" aria-label=\"V-Neck Pure Cotton T-shirt\"><img fetchpriority=\"high\" decoding=\"async\" width=\"420\" height=\"560\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail front-image\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg 720w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1-90x120.jpg 90w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/><img decoding=\"async\" width=\"420\" height=\"560\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-420x560.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail hover-image\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-420x560.jpg 420w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-240x320.jpg 240w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-435x580.jpg 435w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-90x120.jpg 90w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2.jpg 720w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/><\/a>\t\t<div class=\"pls-product-icons\">\n\t\t\t\t\t\r\n\t\t<div class=\"pls-whishlist-btn\">\r\n\t\t\t<a href=\"?add-to-wishlist=1172\" class=\"woosw-btn woosw-btn-1172\" data-id=\"1172\" data-product_name=\"V-Neck Pure Cotton T-shirt\" data-product_image=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" rel=\"nofollow\" aria-label=\"Add to wishlist\">Add to wishlist<\/a>\t\t<\/div>\t\t\r\n\t\t\t\r\n\t\t<div class=\"pls-compare-btn\">\r\n\t\t\t<a href=\"?add-to-compare=1172\" class=\"woosc-btn woosc-btn-1172 \" rel=\"nofollow\" data-text=\"Compare\" data-text_added=\"Compare\" data-id=\"1172\" data-product_id=\"1172\" data-product_name=\"V-Neck Pure Cotton T-shirt\" data-product_image=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\">Compare<\/a>\t\t<\/div>\r\n\t\t\t\t\r\n\t\t<div class=\"pls-quickview-button\">\r\n\t\t\t<a class=\"pls-quickview-btn \" href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/v-neck-pure-cotton-t-shirt\/\" data-id=\"1172\">Quick View<\/a>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"pls-product-actions\">\n\t\t\t\t\t\r\n\t\t<div class=\"pls-cart-button\">\r\n\t\t\t<a href=\"\/dummy\/wp-json\/wp\/v2\/pages\/31?add-to-cart=1172\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1172\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"1172\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;V-Neck Pure Cotton T-shirt&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;V-Neck Pure Cotton T-shirt&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t\t <\/div>\r\n\t\t\t\t<\/div>\n\t<\/div>\n\t<div class=\"pls-product-info\">\n\t\t<h3 class=\"product-title\"><a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/v-neck-pure-cotton-t-shirt\/\" target=\"_self\">V-Neck Pure Cotton T-shirt<\/a><\/h3>\n<div class=\"pls-star-rating\">\n\t<div class=\"star-rating\" role=\"img\" aria-label=\"Rated 0 out of 5\"><span style=\"width:0%\">Rated <strong class=\"rating\">0<\/strong> out of 5<\/span><\/div>\t\t<span class=\"rating-counts\">\n\t\t\t(0)\t\t<\/span>\n\t<\/div>\n\t<div class=\"pls-product-price\">\n\t\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>59.99<\/span><\/span>\n\t<\/div>\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\t \n<\/div>\n\n<div class=\"swiper-slide product type-product post-1170 status-publish instock product_cat-accessories product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-simple\">\t \n\t\n<div class=\"pls-product-inner\">\n\t\t\n\t<div class=\"pls-product-image\">\n\t\t<div class=\"pls-product-labels\"><span class=\"on-sale\">-20% <\/span><\/div><a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/polarized-sunglasses\/\" class=\"woocommerce-LoopProduct-link\" target=\"_self\" aria-label=\"Polarized Sunglasses\"><img fetchpriority=\"high\" decoding=\"async\" width=\"420\" height=\"560\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail front-image\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg 720w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1-90x120.jpg 90w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/><img decoding=\"async\" width=\"420\" height=\"560\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-420x560.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail hover-image\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-420x560.jpg 420w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-240x320.jpg 240w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-435x580.jpg 435w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-90x120.jpg 90w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2.jpg 720w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/><\/a>\t\t<div class=\"pls-product-icons\">\n\t\t\t\t\t\r\n\t\t<div class=\"pls-whishlist-btn\">\r\n\t\t\t<a href=\"?add-to-wishlist=1170\" class=\"woosw-btn woosw-btn-1170\" data-id=\"1170\" data-product_name=\"Polarized Sunglasses\" data-product_image=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" rel=\"nofollow\" aria-label=\"Add to wishlist\">Add to wishlist<\/a>\t\t<\/div>\t\t\r\n\t\t\t\r\n\t\t<div class=\"pls-compare-btn\">\r\n\t\t\t<a href=\"?add-to-compare=1170\" class=\"woosc-btn woosc-btn-1170 \" rel=\"nofollow\" data-text=\"Compare\" data-text_added=\"Compare\" data-id=\"1170\" data-product_id=\"1170\" data-product_name=\"Polarized Sunglasses\" data-product_image=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\">Compare<\/a>\t\t<\/div>\r\n\t\t\t\t\r\n\t\t<div class=\"pls-quickview-button\">\r\n\t\t\t<a class=\"pls-quickview-btn \" href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/polarized-sunglasses\/\" data-id=\"1170\">Quick View<\/a>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t\r\n\t\t<div class=\"pls-product-sale-marquee\">\r\n\t\t\t<div class=\"pls-marquee\">\r\n\t\t\t\t<div class=\"pls-marquee-items\">\r\n\t\t\t\t\t<div class=\"pls-marquee-item\">Hot Sale <span class=\"on-sale\">20% <\/span> off.<\/div><div class=\"pls-marquee-separator\"><\/div><div class=\"pls-marquee-item\">Hot Sale <span class=\"on-sale\">20% <\/span> off.<\/div><div class=\"pls-marquee-separator\"><\/div><div class=\"pls-marquee-item\">Hot Sale <span class=\"on-sale\">20% <\/span> off.<\/div><div class=\"pls-marquee-separator\"><\/div><div class=\"pls-marquee-item\">Hot Sale <span class=\"on-sale\">20% <\/span> off.<\/div><div class=\"pls-marquee-separator\"><\/div><div class=\"pls-marquee-item\">Hot Sale <span class=\"on-sale\">20% <\/span> off.<\/div><div class=\"pls-marquee-separator\"><\/div>\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"pls-marquee\">\r\n\t\t\t\t<div class=\"pls-marquee-items\">\r\n\t\t\t\t\t<div class=\"pls-marquee-item\">Hot Sale <span class=\"on-sale\">20% <\/span> off.<\/div><div class=\"pls-marquee-separator\"><\/div><div class=\"pls-marquee-item\">Hot Sale <span class=\"on-sale\">20% <\/span> off.<\/div><div class=\"pls-marquee-separator\"><\/div><div class=\"pls-marquee-item\">Hot Sale <span class=\"on-sale\">20% <\/span> off.<\/div><div class=\"pls-marquee-separator\"><\/div><div class=\"pls-marquee-item\">Hot Sale <span class=\"on-sale\">20% <\/span> off.<\/div><div class=\"pls-marquee-separator\"><\/div><div class=\"pls-marquee-item\">Hot Sale <span class=\"on-sale\">20% <\/span> off.<\/div><div class=\"pls-marquee-separator\"><\/div>\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div> \r\n\t\t\t\t\t\t<div class=\"pls-product-actions\">\n\t\t\t\t\t\r\n\t\t<div class=\"pls-cart-button\">\r\n\t\t\t<a href=\"\/dummy\/wp-json\/wp\/v2\/pages\/31?add-to-cart=1170\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1170\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"1170\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Polarized Sunglasses&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Polarized Sunglasses&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t\t <\/div>\r\n\t\t\t\t<\/div>\n\t<\/div>\n\t<div class=\"pls-product-info\">\n\t\t<h3 class=\"product-title\"><a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/polarized-sunglasses\/\" target=\"_self\">Polarized Sunglasses<\/a><\/h3>\n<div class=\"pls-star-rating\">\n\t<div class=\"star-rating\" role=\"img\" aria-label=\"Rated 0 out of 5\"><span style=\"width:0%\">Rated <strong class=\"rating\">0<\/strong> out of 5<\/span><\/div>\t\t<span class=\"rating-counts\">\n\t\t\t(0)\t\t<\/span>\n\t<\/div>\n\t<div class=\"pls-product-price\">\n\t\t<span class=\"price\"><ins><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>79.99<\/span><\/ins> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>99.99<\/span><\/del><\/span>\n\t<\/div>\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\t \n<\/div>\n\n<div class=\"swiper-slide product type-product post-1169 status-publish instock product_cat-clothing product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable has-default-attributes\">\t \n\t\n<div class=\"pls-product-inner\">\n\t\t\n\t<div class=\"pls-product-image\">\n\t\t<div class=\"pls-product-labels\"><span class=\"on-sale\">-44% <\/span><\/div><a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/ramie-shirt-with-pockets\/\" class=\"woocommerce-LoopProduct-link\" target=\"_self\" aria-label=\"Ramie Shirt with Pockets\"><img fetchpriority=\"high\" decoding=\"async\" width=\"420\" height=\"560\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail front-image\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg 720w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1-90x120.jpg 90w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/><img decoding=\"async\" width=\"420\" height=\"560\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-420x560.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail hover-image\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-420x560.jpg 420w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-240x320.jpg 240w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-435x580.jpg 435w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2-90x120.jpg 90w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-2.jpg 720w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/><\/a>\t\t\t\t<div class=\"pls-product-countdown-timer\">\r\n\t\t\t\t\t<div class=\"pls-product-countdown\" data-end-date=\"2027-12-31 23:59:59\" data-timezone=\"+00:00\" data-countdown-style=\"countdown-text\"><\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"pls-product-icons\">\n\t\t\t\t\t\r\n\t\t<div class=\"pls-whishlist-btn\">\r\n\t\t\t<a href=\"?add-to-wishlist=1169\" class=\"woosw-btn woosw-btn-1169\" data-id=\"1169\" data-product_name=\"Ramie Shirt with Pockets\" data-product_image=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" rel=\"nofollow\" aria-label=\"Add to wishlist\">Add to wishlist<\/a>\t\t<\/div>\t\t\r\n\t\t\t\r\n\t\t<div class=\"pls-compare-btn\">\r\n\t\t\t<a href=\"?add-to-compare=1169\" class=\"woosc-btn woosc-btn-1169 \" rel=\"nofollow\" data-text=\"Compare\" data-text_added=\"Compare\" data-id=\"1169\" data-product_id=\"1169\" data-product_name=\"Ramie Shirt with Pockets\" data-product_image=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\">Compare<\/a>\t\t<\/div>\r\n\t\t\t\t\r\n\t\t<div class=\"pls-quickview-button\">\r\n\t\t\t<a class=\"pls-quickview-btn \" href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/ramie-shirt-with-pockets\/\" data-id=\"1169\">Quick View<\/a>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"pls-product-actions\">\n\t\t\t\t\t\r\n\t\t<div class=\"pls-cart-button\">\r\n\t\t\t<a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/ramie-shirt-with-pockets\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1169\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"1169\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Ramie Shirt with Pockets&rdquo;\" rel=\"nofollow\">Select options<\/a>\t\t <\/div>\r\n\t\t\t\t<\/div>\n\t<\/div>\n\t<div class=\"pls-product-info\">\n\t\t<h3 class=\"product-title\"><a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/ramie-shirt-with-pockets\/\" target=\"_self\">Ramie Shirt with Pockets<\/a><\/h3>\n<div class=\"pls-star-rating\">\n\t<div class=\"star-rating\" role=\"img\" aria-label=\"Rated 0 out of 5\"><span style=\"width:0%\">Rated <strong class=\"rating\">0<\/strong> out of 5<\/span><\/div>\t\t<span class=\"rating-counts\">\n\t\t\t(0)\t\t<\/span>\n\t<\/div>\n\t<div class=\"pls-product-price\">\n\t\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>49.99<\/span> <span aria-hidden=\"true\">&ndash;<\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>89.99<\/span><span class=\"screen-reader-text\">Price range: &#036;49.99 through &#036;89.99<\/span><\/span>\n\t<\/div>\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\t \n<\/div>\n\n<div class=\"swiper-slide product type-product post-1168 status-publish last instock product_cat-women has-post-thumbnail shipping-taxable purchasable product-type-variable has-default-attributes\">\t \n\t\n<div class=\"pls-product-inner\">\n\t\t\n\t<div class=\"pls-product-image\">\n\t\t<a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/shoulder-straps-fitted-top\/\" class=\"woocommerce-LoopProduct-link\" target=\"_self\" aria-label=\"Shoulder Straps Fitted Top\"><img fetchpriority=\"high\" decoding=\"async\" width=\"420\" height=\"560\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail front-image\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg 720w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1-90x120.jpg 90w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/><img decoding=\"async\" width=\"420\" height=\"560\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail hover-image\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg 720w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1-90x120.jpg 90w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/><\/a>\t\t<div class=\"pls-product-icons\">\n\t\t\t\t\t\r\n\t\t<div class=\"pls-whishlist-btn\">\r\n\t\t\t<a href=\"?add-to-wishlist=1168\" class=\"woosw-btn woosw-btn-1168\" data-id=\"1168\" data-product_name=\"Shoulder Straps Fitted Top\" data-product_image=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" rel=\"nofollow\" aria-label=\"Add to wishlist\">Add to wishlist<\/a>\t\t<\/div>\t\t\r\n\t\t\t\r\n\t\t<div class=\"pls-compare-btn\">\r\n\t\t\t<a href=\"?add-to-compare=1168\" class=\"woosc-btn woosc-btn-1168 \" rel=\"nofollow\" data-text=\"Compare\" data-text_added=\"Compare\" data-id=\"1168\" data-product_id=\"1168\" data-product_name=\"Shoulder Straps Fitted Top\" data-product_image=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\">Compare<\/a>\t\t<\/div>\r\n\t\t\t\t\r\n\t\t<div class=\"pls-quickview-button\">\r\n\t\t\t<a class=\"pls-quickview-btn \" href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/shoulder-straps-fitted-top\/\" data-id=\"1168\">Quick View<\/a>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"pls-product-actions\">\n\t\t\t\t\t\r\n\t\t<div class=\"pls-cart-button\">\r\n\t\t\t<a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/shoulder-straps-fitted-top\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1168\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"1168\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Shoulder Straps Fitted Top&rdquo;\" rel=\"nofollow\">Select options<\/a>\t\t <\/div>\r\n\t\t\t\t<\/div>\n\t<\/div>\n\t<div class=\"pls-product-info\">\n\t\t<h3 class=\"product-title\"><a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/shoulder-straps-fitted-top\/\" target=\"_self\">Shoulder Straps Fitted Top<\/a><\/h3>\n<div class=\"pls-star-rating\">\n\t<div class=\"star-rating\" role=\"img\" aria-label=\"Rated 0 out of 5\"><span style=\"width:0%\">Rated <strong class=\"rating\">0<\/strong> out of 5<\/span><\/div>\t\t<span class=\"rating-counts\">\n\t\t\t(0)\t\t<\/span>\n\t<\/div>\n\t<div class=\"pls-product-price\">\n\t\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>69.99<\/span><\/span>\n\t<\/div>\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\t \n<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f850dc5 e-flex e-con-boxed e-con e-parent\" data-id=\"f850dc5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ecb5cf elementor-widget elementor-widget-pls-heading\" data-id=\"9ecb5cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-header-16168\" class=\"pls-element pls-heading pls-text-center\">\t\n\t\t\t\n\t\t\t<div class=\"heading-wrap\">\n\t\t\t<h2 class=\"heading-title\">Customer Say!<\/h2>\t\t<\/div>\n\t\t\n    \t\t<div class=\"heading-tagline\"> Our customers adore our products, and we constantly aim to delight them. <\/div>\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68ae0a1 elementor-widget elementor-widget-pls-testimonials\" data-id=\"68ae0a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-testimonials.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-testimonials-2764\" class=\"pls-element pls-testimonials pls-testimonial-style-1\">\n\t<div class=\"section-content row swiper pls-slider\">\t\n\t\t<div class=\"swiper-wrapper slider-col-lg-3 slider-col-md-2 slider-col-1\" data-slider_options=\"{&quot;slider_loop&quot;:false,&quot;slider_autoplay&quot;:false,&quot;slider_autoplay_delay&quot;:&quot;1500&quot;,&quot;slider_autoplay_speed&quot;:&quot;1500&quot;,&quot;slider_pause_on_hover&quot;:false,&quot;slider_rewind&quot;:false,&quot;slider_autoHeigh&quot;:false,&quot;slider_touchDrag&quot;:true,&quot;slider_touchDrag_mobile&quot;:true,&quot;slider_navigation&quot;:true,&quot;slider_pagination&quot;:true,&quot;slider_scrollbar&quot;:false,&quot;slider_centered&quot;:false,&quot;slider_effect&quot;:&quot;slide&quot;,&quot;slider_spaceBetween&quot;:0,&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_show_tablet&quot;:2,&quot;slides_to_show_mobile&quot;:1,&quot;slides_to_scroll&quot;:1}\" >\n\t\t\t<div class=\"pls-client swiper-slide\">\t\n\t<div class=\"pls-client-wrap\">\t\t\n\t\t\t\t\t<div class=\"pls-client-rating woocommerce\"> \n\t\t\t\t<div class=\"star-rating\">\n\t\t\t\t\t<span style=\"width:100%\"><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t<div class=\"pls-client-quote\">\n\t\t\t\"Fantastic shop! Great selection, fair prices, and friendly staff. Highly recommended. The quality of the products is exceptional, and the prices are very reasonable!\"\t\t<\/div>\n\t\t\t\t\t<div class=\"pls-client-name\">Donald Duclk<\/div>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"pls-testimonial-product\">\n\t\t\t\t<div class=\"pls-product-image\">\n\t\t\t\t\t<a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/double-breasted-trench-coat\/\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"113\" height=\"150\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Double-Breasted Trench Coat\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg 720w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1-90x120.jpg 90w\" sizes=\"(max-width: 113px) 100vw, 113px\" \/>\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"pls-product-info\">\n\t\t\t\t\t<div class=\"product-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/double-breasted-trench-coat\/\">\n\t\t\t\t\t\t\tDouble-Breasted Trench Coat\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"product-price\">\n\t\t\t\t\t\t<ins><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span>189.99<\/bdi><\/span><\/ins> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span>219.99<\/bdi><\/span><\/del>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\n\t<\/div>\t\n<\/div><div class=\"pls-client swiper-slide\">\t\n\t<div class=\"pls-client-wrap\">\t\t\n\t\t\t\t\t<div class=\"pls-client-rating woocommerce\"> \n\t\t\t\t<div class=\"star-rating\">\n\t\t\t\t\t<span style=\"width:80%\"><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t<div class=\"pls-client-quote\">\n\t\t\t\"I absolutely love this shop! The products are high-quality and the customer service is excellent. I always leave with exactly what I need and a smile on my face.\"\t\t<\/div>\n\t\t\t\t\t<div class=\"pls-client-name\">Niamh Oxley<\/div>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"pls-testimonial-product\">\n\t\t\t\t<div class=\"pls-product-image\">\n\t\t\t\t\t<a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/ribbed-cotton-blend-top\/\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"113\" height=\"150\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Ribbed Cotton-Blend Top\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg 720w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1-90x120.jpg 90w\" sizes=\"(max-width: 113px) 100vw, 113px\" \/>\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"pls-product-info\">\n\t\t\t\t\t<div class=\"product-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/ribbed-cotton-blend-top\/\">\n\t\t\t\t\t\t\tRibbed Cotton-Blend Top\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"product-price\">\n\t\t\t\t\t\t<span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span>69.99<\/bdi><\/span>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\n\t<\/div>\t\n<\/div><div class=\"pls-client swiper-slide\">\t\n\t<div class=\"pls-client-wrap\">\t\t\n\t\t\t\t\t<div class=\"pls-client-rating woocommerce\"> \n\t\t\t\t<div class=\"star-rating\">\n\t\t\t\t\t<span style=\"width:100%\"><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t<div class=\"pls-client-quote\">\n\t\t\t\"I love this shop! Top-quality products and incredibly friendly staff. They always go the extra mile to ensure I'm satisfied with my purchase.\"\t\t<\/div>\n\t\t\t\t\t<div class=\"pls-client-name\">Donald Duclk<\/div>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"pls-testimonial-product\">\n\t\t\t\t<div class=\"pls-product-image\">\n\t\t\t\t\t<a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/v-neck-pure-cotton-t-shirt\/\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"113\" height=\"150\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"V-Neck Pure Cotton T-shirt\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg 720w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1-90x120.jpg 90w\" sizes=\"(max-width: 113px) 100vw, 113px\" \/>\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"pls-product-info\">\n\t\t\t\t\t<div class=\"product-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/v-neck-pure-cotton-t-shirt\/\">\n\t\t\t\t\t\t\tV-Neck Pure Cotton T-shirt\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"product-price\">\n\t\t\t\t\t\t<span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span>59.99<\/bdi><\/span>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\n\t<\/div>\t\n<\/div><div class=\"pls-client swiper-slide\">\t\n\t<div class=\"pls-client-wrap\">\t\t\n\t\t\t\t\t<div class=\"pls-client-rating woocommerce\"> \n\t\t\t\t<div class=\"star-rating\">\n\t\t\t\t\t<span style=\"width:100%\"><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t<div class=\"pls-client-quote\">\n\t\t\t\"Fantastic shop! Great selection, fair prices, and friendly staff. Highly recommended. The quality of the products is exceptional, and the prices are very reasonable!\"\t\t<\/div>\n\t\t\t\t\t<div class=\"pls-client-name\">Donald Duclk<\/div>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"pls-testimonial-product\">\n\t\t\t\t<div class=\"pls-product-image\">\n\t\t\t\t\t<a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/double-breasted-trench-coat\/\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"113\" height=\"150\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Double-Breasted Trench Coat\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1.jpg 720w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/02\/product-image-1-90x120.jpg 90w\" sizes=\"(max-width: 113px) 100vw, 113px\" \/>\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"pls-product-info\">\n\t\t\t\t\t<div class=\"product-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/modave.presslayouts.com\/dummy\/product\/double-breasted-trench-coat\/\">\n\t\t\t\t\t\t\tDouble-Breasted Trench Coat\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"product-price\">\n\t\t\t\t\t\t<ins><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span>189.99<\/bdi><\/span><\/ins> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span>219.99<\/bdi><\/span><\/del>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\n\t<\/div>\t\n<\/div>\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f30d345 e-con-full e-flex e-con e-parent\" data-id=\"f30d345\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a79d632 elementor-widget elementor-widget-pls-banner-slider\" data-id=\"a79d632\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-banner-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-banners-slider-26742\" class=\"row pls-element pls-banners-slider swiper pls-slider\">\n\t<div class=\"swiper-wrapper slider-col-lg-2 slider-col-md-2 slider-col-1\" data-slider_options=\"{&quot;slider_loop&quot;:false,&quot;slider_autoplay&quot;:false,&quot;slider_autoplay_delay&quot;:&quot;1500&quot;,&quot;slider_autoplay_speed&quot;:&quot;1500&quot;,&quot;slider_pause_on_hover&quot;:true,&quot;slider_rewind&quot;:false,&quot;slider_autoHeigh&quot;:false,&quot;slider_touchDrag&quot;:true,&quot;slider_touchDrag_mobile&quot;:true,&quot;slider_navigation&quot;:true,&quot;slider_pagination&quot;:false,&quot;slider_scrollbar&quot;:false,&quot;slider_centered&quot;:false,&quot;slider_effect&quot;:&quot;slide&quot;,&quot;slider_spaceBetween&quot;:0,&quot;slides_to_show&quot;:&quot;2&quot;,&quot;slides_to_show_tablet&quot;:2,&quot;slides_to_show_mobile&quot;:1,&quot;slides_to_scroll&quot;:1}\" >\n\t\t<div id=\"pls-banner-39823\" class=\"pls-element pls-banner swiper-slide elementor-repeater-item-8b7527b banner-zoom-out\">\n\t<div class=\"banner-wrapper\" >\n\t\t\t\t\t<div class=\"banner-image-wrap\">\t\t\t\n\t\t\t\t<div class=\"banner-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"905\" height=\"637\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fasion-12-banner.jpg\" class=\"attachment-full size-full \" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fasion-12-banner.jpg 905w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fasion-12-banner-455x320.jpg 455w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fasion-12-banner-824x580.jpg 824w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fasion-12-banner-768x541.jpg 768w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fasion-12-banner-420x296.jpg 420w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fasion-12-banner-720x507.jpg 720w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fasion-12-banner-90x63.jpg 90w\" sizes=\"(max-width: 905px) 100vw, 905px\" \/>\t\t\t\t<\/div>\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"banner-content-wrap\">\n\t\t\t\t<div class=\"banner-content\">\n\t\t\t\t\t<div class=\"banner-content-top\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"banner-title-wrap\">\n\t\t\t\t\t\t\t<h3 class=\"banner-title\"> What's New<\/h3>\n\t\t\t\t\t\t<\/div>\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"banner-content-text\">\n\t\t\t\t\t\t\t\tReserved for special occasions\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"banner-content-bottom\">\n\t\t\t\t\t\t\t<div class=\"banner-button pls-button\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_self\" class=\"button btn-style-link\">Shop Now<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n<div id=\"pls-banner-45489\" class=\"pls-element pls-banner swiper-slide elementor-repeater-item-be9958e banner-zoom-out\">\n\t<div class=\"banner-wrapper\" >\n\t\t\t\t\t<div class=\"banner-image-wrap\">\t\t\t\n\t\t\t\t<div class=\"banner-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"905\" height=\"637\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fasion-12-banner.jpg\" class=\"attachment-full size-full \" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fasion-12-banner.jpg 905w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fasion-12-banner-455x320.jpg 455w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fasion-12-banner-824x580.jpg 824w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fasion-12-banner-768x541.jpg 768w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fasion-12-banner-420x296.jpg 420w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fasion-12-banner-720x507.jpg 720w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fasion-12-banner-90x63.jpg 90w\" sizes=\"(max-width: 905px) 100vw, 905px\" \/>\t\t\t\t<\/div>\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"banner-content-wrap\">\n\t\t\t\t<div class=\"banner-content\">\n\t\t\t\t\t<div class=\"banner-content-top\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"banner-title-wrap\">\n\t\t\t\t\t\t\t<h3 class=\"banner-title\"> Capsule Collection<\/h3>\n\t\t\t\t\t\t<\/div>\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"banner-content-text\">\n\t\t\t\t\t\t\t\tFrom beach to party: Perfect styles for every occasion\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"banner-content-bottom\">\n\t\t\t\t\t\t\t<div class=\"banner-button pls-button\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_self\" class=\"button btn-style-link\">Shop Now<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-10eabe1 e-grid e-con-boxed e-con e-parent\" data-id=\"10eabe1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-030e561 elementor-widget elementor-widget-pls-infobox\" data-id=\"030e561\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-info-box-25470\" class=\"pls-element pls-info-box icon-effect-none icon-custom icon-left color-scheme-inherit hover-color-scheme-inherit\">\n\t<div class=\"info-box-wrap\"  >\n\t\t<div class=\"box-icon-wrap\">\n\t\t\t\t\t\t\t<div class=\"info-box-icon\"><img decoding=\"async\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/01\/ArrowUDownLeft.svg\" alt=\"14-Day Returns\"\/><\/div>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-title mb\" >\t\t\t\t\n\t\t\t\t\t<h4>14-Day Returns<\/h4>\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-description mb\">\n\t\t\t\t\t<p>Risk-free shopping with easy returns.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d44001 elementor-widget elementor-widget-pls-infobox\" data-id=\"1d44001\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-info-box-54316\" class=\"pls-element pls-info-box icon-effect-none icon-custom icon-left color-scheme-inherit hover-color-scheme-inherit\">\n\t<div class=\"info-box-wrap\"  >\n\t\t<div class=\"box-icon-wrap\">\n\t\t\t\t\t\t\t<div class=\"info-box-icon\"><img decoding=\"async\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/01\/Truck.svg\" alt=\"Free Shipping\"\/><\/div>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-title mb\" >\t\t\t\t\n\t\t\t\t\t<h4>Free Shipping<\/h4>\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-description mb\">\n\t\t\t\t\t<p>No extra costs, just the price you see.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3697825 elementor-widget elementor-widget-pls-infobox\" data-id=\"3697825\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-info-box-33743\" class=\"pls-element pls-info-box icon-effect-none icon-custom icon-left color-scheme-inherit hover-color-scheme-inherit\">\n\t<div class=\"info-box-wrap\"  >\n\t\t<div class=\"box-icon-wrap\">\n\t\t\t\t\t\t\t<div class=\"info-box-icon\"><img decoding=\"async\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/01\/Headset.svg\" alt=\"24\/7 Support\"\/><\/div>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-title mb\" >\t\t\t\t\n\t\t\t\t\t<h4>24\/7 Support<\/h4>\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-description mb\">\n\t\t\t\t\t<p>24\/7 support, always here just for you<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85b5375 elementor-widget elementor-widget-pls-infobox\" data-id=\"85b5375\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-info-box-74628\" class=\"pls-element pls-info-box icon-effect-none icon-custom icon-left color-scheme-inherit hover-color-scheme-inherit\">\n\t<div class=\"info-box-wrap\"  >\n\t\t<div class=\"box-icon-wrap\">\n\t\t\t\t\t\t\t<div class=\"info-box-icon\"><img decoding=\"async\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/01\/SealCheck.svg\" alt=\"Member Discounts\"\/><\/div>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-title mb\" >\t\t\t\t\n\t\t\t\t\t<h4>Member Discounts<\/h4>\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-description mb\">\n\t\t\t\t\t<p>Special prices for our loyal customers.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9ecc46b e-con-full e-flex e-con e-parent\" data-id=\"9ecc46b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5858db3 elementor-widget elementor-widget-pls-heading\" data-id=\"5858db3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pls-header-6652\" class=\"pls-element pls-heading pls-text-center\">\t\n\t\t\t\n\t\t\t<div class=\"heading-wrap\">\n\t\t\t<h2 class=\"heading-title\">Shop Instagram<\/h2>\t\t<\/div>\n\t\t\n    \t\t<div class=\"heading-tagline\"> Elevate your wardrobe with fresh finds today! <\/div>\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9d01ad elementor-widget elementor-widget-pls-instagram-shop\" data-id=\"a9d01ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pls-instagram-shop.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section id=\"pls-instagram-shop-54345\" class=\"pls-element pls-instagram pls-instagram-shop\">\n\t<div class=\"section-content  pls-slider swiper row\">\n\t\t<div class=\"pls-instagram-wrap swiper-wrapper slider-col-lg-6 slider-col-md-3 slider-col-2\" data-slider_options=\"{&quot;slider_loop&quot;:false,&quot;slider_autoplay&quot;:false,&quot;slider_autoplay_delay&quot;:&quot;1500&quot;,&quot;slider_autoplay_speed&quot;:&quot;1500&quot;,&quot;slider_pause_on_hover&quot;:false,&quot;slider_rewind&quot;:false,&quot;slider_autoHeigh&quot;:false,&quot;slider_touchDrag&quot;:true,&quot;slider_touchDrag_mobile&quot;:true,&quot;slider_navigation&quot;:true,&quot;slider_pagination&quot;:false,&quot;slider_scrollbar&quot;:false,&quot;slider_centered&quot;:false,&quot;slider_effect&quot;:&quot;slide&quot;,&quot;slider_spaceBetween&quot;:0,&quot;slides_to_show&quot;:&quot;6&quot;,&quot;slides_to_show_tablet&quot;:3,&quot;slides_to_show_mobile&quot;:2,&quot;slides_to_scroll&quot;:1}\" >\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pls-instagram-image swiper-slide\">\n\t\t\t\t\t\t<div class=\"pls-insta-image-wrap\">\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram.jpg 320w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram-150x150.jpg 150w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram-90x90.jpg 90w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram-96x96.jpg 96w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><span class=\"pls-quickview-btn\" data-id=\"1086\">Quick View<\/span>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pls-instagram-image swiper-slide\">\n\t\t\t\t\t\t<div class=\"pls-insta-image-wrap\">\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram.jpg 320w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram-150x150.jpg 150w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram-90x90.jpg 90w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram-96x96.jpg 96w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><span class=\"pls-quickview-btn\" data-id=\"1081\">Quick View<\/span>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pls-instagram-image swiper-slide\">\n\t\t\t\t\t\t<div class=\"pls-insta-image-wrap\">\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram.jpg 320w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram-150x150.jpg 150w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram-90x90.jpg 90w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram-96x96.jpg 96w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><span class=\"pls-quickview-btn\" data-id=\"1087\">Quick View<\/span>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pls-instagram-image swiper-slide\">\n\t\t\t\t\t\t<div class=\"pls-insta-image-wrap\">\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram.jpg 320w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram-150x150.jpg 150w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram-90x90.jpg 90w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram-96x96.jpg 96w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><span class=\"pls-quickview-btn\" data-id=\"1170\">Quick View<\/span>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pls-instagram-image swiper-slide\">\n\t\t\t\t\t\t<div class=\"pls-insta-image-wrap\">\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram.jpg 320w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram-150x150.jpg 150w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram-90x90.jpg 90w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram-96x96.jpg 96w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><span class=\"pls-quickview-btn\" data-id=\"1084\">Quick View<\/span>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pls-instagram-image swiper-slide\">\n\t\t\t\t\t\t<div class=\"pls-insta-image-wrap\">\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram.jpg 320w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram-150x150.jpg 150w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram-90x90.jpg 90w, https:\/\/modave.presslayouts.com\/dummy\/wp-content\/uploads\/2025\/05\/fashion-1-instagram-96x96.jpg 96w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><span class=\"pls-quickview-btn\" data-id=\"1084\">Quick View<\/span>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Winter Warmth Stay cozy and fashionable with our winter collection. Explore Collection Today&#8217;s Top Picks Fresh styles just in! Elevate your look. Hot Browse wishlist Compare Quick View Add to<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-31","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/modave.presslayouts.com\/dummy\/wp-json\/wp\/v2\/pages\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modave.presslayouts.com\/dummy\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/modave.presslayouts.com\/dummy\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/modave.presslayouts.com\/dummy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/modave.presslayouts.com\/dummy\/wp-json\/wp\/v2\/comments?post=31"}],"version-history":[{"count":0,"href":"https:\/\/modave.presslayouts.com\/dummy\/wp-json\/wp\/v2\/pages\/31\/revisions"}],"wp:attachment":[{"href":"https:\/\/modave.presslayouts.com\/dummy\/wp-json\/wp\/v2\/media?parent=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}